{"id":40271,"date":"2025-07-08T12:48:54","date_gmt":"2025-07-08T18:48:54","guid":{"rendered":"https:\/\/zeyco.com\/?post_type=product&#038;p=40271"},"modified":"2025-07-08T12:52:13","modified_gmt":"2025-07-08T18:52:13","slug":"elevador-p-raices-heidbrink-recto-maestrale-2-5-mm","status":"publish","type":"product","link":"https:\/\/zeyco.com\/en\/producto\/elevador-p-raices-heidbrink-recto-maestrale-2-5-mm\/","title":{"rendered":"Elevador P\/Ra\u00edces Heidbrink Recto Maestrale 2.5 mm"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]La gama de elevaores apicales Heidbrink Medesy es adecuado para realizar de forma efficaz extracciones de peque\u00f1os fragmentos de raices.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;36574&#8243; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;8%&#8221; right_padding_desktop=&#8221;8%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fast&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-right&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;36578&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;85%&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-left&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; delay=&#8221;400&#8243;][image_with_animation image_url=&#8221;36582&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;85%&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<h5>Cod. 700\/8.SL<\/h5>\n<div class=\"woocommerce-product-details__short-description\">\n<p>La gama de elevadores apicales Heidbrink Medesy es adecuado para realizar de forma eficaz extracciones de peque\u00f1os fragmentos de ra\u00edces.<\/p>\n<ul>\n<li class=\"ewa-rteLine\">\n<div class=\"ewa-rteLine\">Afilado perfecto.<\/div>\n<\/li>\n<li class=\"ewa-rteLine\">\n<div class=\"ewa-rteLine\">Puntas rematadas a mano por nuestros artesanos.<\/div>\n<\/li>\n<li class=\"ewa-rteLine\">\n<div class=\"ewa-rteLine\">Mango con dise\u00f1o MAESTRALE. Mango cient\u00edficamente estudiado y realizado con dos diferentes materiales pl\u00e1sticos y con di\u00e1metro aumentado. El agarre es a\u00fan m\u00e1s c\u00f3modo, en la mano del usuario es mucho m\u00e1s firme y seguro.<\/div>\n<\/li>\n<\/ul>\n<\/div>\n","protected":false},"featured_media":40276,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[557],"product_cat":[200,560,259,556,199,266],"product_tag":[],"class_list":{"0":"post-40271","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-medesy","7":"product_cat-cirugia-oral-y-maxilofacial","8":"product_cat-cirugia-e-implantologia","9":"product_cat-instrumentos-2","10":"product_cat-medesy","11":"product_cat-periodoncia","12":"product_cat-periodoncia-y-cirugia","14":"first","15":"instock","16":"shipping-taxable","17":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/product\/40271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/comments?post=40271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/media\/40276"}],"wp:attachment":[{"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/media?parent=40271"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/product_brand?post=40271"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/product_cat?post=40271"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zeyco.com\/en\/wp-json\/wp\/v2\/product_tag?post=40271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}